{"id":313,"date":"2024-12-24T08:48:12","date_gmt":"2024-12-24T07:48:12","guid":{"rendered":"https:\/\/ampabenaljatib.org\/?p=313"},"modified":"2024-12-24T08:52:31","modified_gmt":"2024-12-24T07:52:31","slug":"felicitacion-navidad","status":"publish","type":"post","link":"https:\/\/ampabenaljatib.org\/index.php\/2024\/12\/24\/felicitacion-navidad\/","title":{"rendered":"Felicitaci\u00f3n Navide\u00f1a"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Queridas familias del IES Ben Al Jatib,<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la <strong>AMPA Sorolla<\/strong>, queremos desearles unas <strong>felices fiestas navide\u00f1as<\/strong>, llenas de alegr\u00eda, paz y momentos inolvidables junto a sus seres queridos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1200\" src=\"https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-900x1200.jpg\" alt=\"Felicitaci\u00f3n de Navidad\" class=\"wp-image-314\" style=\"width:439px;height:auto\" srcset=\"https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-900x1200.jpg 900w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-375x500.jpg 375w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-225x300.jpg 225w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-768x1024.jpg 768w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-1152x1536.jpg 1152w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-1536x2048.jpg 1536w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-56x75.jpg 56w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad-480x640.jpg 480w, https:\/\/ampabenaljatib.org\/wp-content\/uploads\/2024\/12\/concurso-Navidad.jpg 1728w\" sizes=\"auto, (max-width:767px) 480px, (max-width:900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nos complace compartir con ustedes el <strong>dibujo ganador<\/strong> de nuestro reciente concurso, el cual refleja el talento y la creatividad de nuestros alumnos. \u00a1Enhorabuena a la ganadora <strong>Alba Navarro<\/strong>! Ha <strong>ganado dos entradas <\/strong>para disfrutar del cine. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprovechamos esta ocasi\u00f3n para agradecerles su <strong>apoyo y colaboraci\u00f3n<\/strong> durante todo el a\u00f1o. Su compromiso es fundamental para el desarrollo y bienestar de nuestros estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que la magia de la Navidad ilumine sus hogares y que el A\u00f1o Nuevo les traiga salud, felicidad y \u00e9xitos en todos sus proyectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Feliz Navidad y pr\u00f3spero A\u00f1o Nuevo!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con afecto,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AMPA Sorolla<\/strong><\/p>\n<div class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend pgfw-icon-display pgfw-icon-display--default\" style=\"--pgfw-icon-justify:center;\"><a href=\"https:\/\/ampabenaljatib.org\/wp-json\/wp\/v2\/posts\/313?action=genpdf&#038;id=313\" class=\"pgfw-single-pdf-download-button pgfw-single-pdf-download-button--default pgfw-single-pdf-download-button--icon-only\" title=\"Generar PDF\" style=\"--pgfw-icon-width:25px;--pgfw-icon-height:45px;\" aria-label=\"Download PDF\"><span class=\"pgfw-single-pdf-download-button__media\" aria-hidden=\"true\"><img src=\"https:\/\/ampabenaljatib.org\/wp-content\/plugins\/pdf-generator-for-wp\/admin\/src\/images\/PDF_Tray.svg\" alt=\"\" decoding=\"async\"><\/span><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Queridas familias del IES Ben Al Jatib, Desde la AMPA Sorolla, queremos desearles unas felices fiestas navide\u00f1as, llenas de alegr\u00eda, paz y momentos inolvidables junto a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":314,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concurso"],"_links":{"self":[{"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":3,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":317,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/posts\/313\/revisions\/317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ampabenaljatib.org\/index.php\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}